{"id":1023,"date":"2025-06-12T13:41:20","date_gmt":"2025-06-12T11:41:20","guid":{"rendered":"https:\/\/tecnoras.com\/about-us\/"},"modified":"2025-09-08T13:11:41","modified_gmt":"2025-09-08T11:11:41","slug":"about-us","status":"publish","type":"page","link":"https:\/\/tecnoras.com\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"<style>.kb-row-layout-id32_edcd49-8a > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id32_edcd49-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id32_edcd49-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-4xl, 8rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_edcd49-8a > .kt-row-layout-overlay{opacity:0.30;background-image:url('https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/06\/imgmcollage1-300x227-1.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id32_edcd49-8a .kb-blocks-bg-video-container,.kb-row-layout-id32_edcd49-8a .kb-blocks-bg-slider{display:none;}}@media all and (max-width: 1024px){.kb-row-layout-id32_edcd49-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep{height:80px;}}@media all and (max-width: 1024px){.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id32_edcd49-8a > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_edcd49-8a .kb-blocks-bg-video-container,.kb-row-layout-id32_edcd49-8a .kb-blocks-bg-slider{display:none;}.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep{height:60px;}.kb-row-layout-id32_edcd49-8a .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id32_edcd49-8a alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column32_edab34-9d > .kt-inside-inner-col,.kadence-column32_edab34-9d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_edab34-9d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_edab34-9d > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_edab34-9d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_edab34-9d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_edab34-9d{position:relative;}@media all and (max-width: 1024px){.kadence-column32_edab34-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_edab34-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_edab34-9d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0, .wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0[data-kb-block=\"kb-adv-heading32_7395b2-d0\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0[data-kb-block=\"kb-adv-heading32_7395b2-d0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0[data-kb-block=\"kb-adv-heading32_7395b2-d0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0, .wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0[data-kb-block=\"kb-adv-heading32_7395b2-d0\"]{font-size:80px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0, .wp-block-kadence-advancedheading.kt-adv-heading32_7395b2-d0[data-kb-block=\"kb-adv-heading32_7395b2-d0\"]{font-size:40px;line-height:1.2;}}<\/style>\n<h1 class=\"kt-adv-heading32_7395b2-d0 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading32_7395b2-d0\">About Us | Tecnoras S.A<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b, .wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b[data-kb-block=\"kb-adv-heading32_af0d62-8b\"]{max-width:550px;margin-right:auto;margin-left:auto;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b[data-kb-block=\"kb-adv-heading32_af0d62-8b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading32_af0d62-8b[data-kb-block=\"kb-adv-heading32_af0d62-8b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading32_af0d62-8b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading32_af0d62-8b\">Manufacturers of hard metal tools.<a href=\"https:\/\/startertemplatecloud.com\/e28\/#\"><\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id32_243793-eb > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id32_243793-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id32_243793-eb > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-id32_243793-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id32_243793-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id32_243793-eb > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id32_243793-eb alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-left-golden kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column32_9792d1-97 > .kt-inside-inner-col,.kadence-column32_9792d1-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_9792d1-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_9792d1-97 > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_9792d1-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_9792d1-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_9792d1-97{position:relative;}@media all and (max-width: 1024px){.kadence-column32_9792d1-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_9792d1-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_9792d1-97 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">History and Location<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">At Tecnoras S.A., we have been manufacturing hard metal (tungsten carbide) and steel tools for cold forming metals since our founding in Cornell\u00e0 de Llobregat in July 1987. In 1999, we moved to our current location in an 800 m\u00b2 building in Sant Boi de Llobregat, just a few kilometres from Barcelona Airport and close to major transport links. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Our goal is continuous improvement to meet our customers&#8217; needs. To achieve this, we rely on a team of 20 technically well-trained people, as well as modern machinery with the latest manufacturing processes, close collaboration with our suppliers of raw materials (hard metal and steel) and services (heat treatments and coatings), and careful quality control. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Most of our customers are suppliers to the automotive industry and manufacturers of fasteners, tubes, metal containers, and, in general, processes requiring high-precision tools. Currently, more than 20% of our production is destined for export. <\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column32_580e39-02 > .kt-inside-inner-col,.kadence-column32_580e39-02 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_580e39-02 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_580e39-02 > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_580e39-02 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_580e39-02 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_580e39-02{position:relative;}@media all and (max-width: 1024px){.kadence-column32_580e39-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_580e39-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_580e39-02 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column32_31147e-cd > .kt-inside-inner-col,.kadence-column32_31147e-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_31147e-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_31147e-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_31147e-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_31147e-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_31147e-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column32_31147e-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_31147e-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_31147e-cd\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-id-32_94c201-e1 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-32_94c201-e1 .kb-slide-item .kb-gal-image-radius img{border-radius:20px 20px 20px 20px;;}.kb-gallery-wrap-id-32_94c201-e1.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-32_94c201-e1.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style><div class=\"kb-gallery-wrap-id-32_94c201-e1 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-slider kb-gallery-id-32_94c201-e1 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-none\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-type=\"slider\" data-slider-hover-pause=\"false\" data-slider-auto=\"1\" data-slider-speed=\"7000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-blocks-slider splide__list kt-carousel-arrowstyle-none kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\"><li class=\"kb-slide-item kb-gallery-slide-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta-1024x683.png\" width=\"1024\" height=\"683\" alt=\"Fachada de la planta de tecnoras\" data-full-image=\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta.png\" data-light-image=\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta.png\" data-id=\"1506\" class=\"wp-image-1506 skip-lazy\" srcset=\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta-1024x683.png 1024w, https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta-300x200.png 300w, https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta-768x512.png 768w, https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/08\/foto-sin-furgoneta.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id32_3d06c3-7f > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id32_3d06c3-7f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id32_3d06c3-7f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:1140px;margin-left:auto;margin-right:auto;padding-top:100px;padding-right:0px;padding-bottom:100px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_3d06c3-7f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id32_3d06c3-7f > .kt-row-column-wrap{max-width:700px;margin-left:auto;margin-right:auto;padding-top:80px;padding-right:0px;padding-bottom:80px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id32_3d06c3-7f > .kt-row-column-wrap{padding-top:60px;padding-right:15px;padding-bottom:60px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id32_3d06c3-7f alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column32_419567-7d > .kt-inside-inner-col{display:flex;}.kadence-column32_419567-7d > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_419567-7d > .kt-inside-inner-col,.kadence-column32_419567-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_419567-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_419567-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column32_419567-7d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_419567-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_419567-7d{position:relative;}.kadence-column32_419567-7d, .kt-inside-inner-col > .kadence-column32_419567-7d:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column32_419567-7d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column32_419567-7d, .kt-inside-inner-col > .kadence-column32_419567-7d:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column32_419567-7d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_419567-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_419567-7d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id32_391dc5-c0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id32_391dc5-c0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id32_391dc5-c0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1140px;margin-left:auto;margin-right:auto;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_391dc5-c0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id32_391dc5-c0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id32_391dc5-c0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id32_391dc5-c0 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column32_0ff7d7-15 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_0ff7d7-15 > .kt-inside-inner-col,.kadence-column32_0ff7d7-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_0ff7d7-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_0ff7d7-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_0ff7d7-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_0ff7d7-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_0ff7d7-15{position:relative;}.kadence-column32_0ff7d7-15, .kt-inside-inner-col > .kadence-column32_0ff7d7-15:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:60px;}@media all and (max-width: 1024px){.kadence-column32_0ff7d7-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column32_0ff7d7-15, .kt-inside-inner-col > .kadence-column32_0ff7d7-15:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column32_0ff7d7-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_0ff7d7-15 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee, .wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee[data-kb-block=\"kb-adv-heading32_7d322b-ee\"]{margin-top:-5px;margin-right:0px;margin-bottom:28.5px;margin-left:0px;font-size:var(--global-kb-font-size-lg, 2rem);line-height:50px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee[data-kb-block=\"kb-adv-heading32_7d322b-ee\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee[data-kb-block=\"kb-adv-heading32_7d322b-ee\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee, .wp-block-kadence-advancedheading.kt-adv-heading32_7d322b-ee[data-kb-block=\"kb-adv-heading32_7d322b-ee\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading32_7d322b-ee wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading32_7d322b-ee\">We offer:<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id32_b8fcb3-3d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id32_b8fcb3-3d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id32_b8fcb3-3d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:20px;padding-right:30px;padding-bottom:20px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id32_b8fcb3-3d{border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;isolation:isolate;}.kb-row-layout-id32_b8fcb3-3d > .kt-row-layout-overlay{border-top-left-radius:6px;border-top-right-radius:6px;border-bottom-right-radius:6px;border-bottom-left-radius:6px;}.kb-row-layout-id32_b8fcb3-3d > .kt-row-layout-overlay{opacity:0.00;mix-blend-mode:normal;}@media all and (max-width: 1024px){.kb-row-layout-id32_b8fcb3-3d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id32_b8fcb3-3d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id32_b8fcb3-3d {box-shadow: 20px 20px 80px 0px rgba(0, 0, 0, 0.1);}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id32_b8fcb3-3d alignwide has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column32_de503c-bb > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_de503c-bb > .kt-inside-inner-col,.kadence-column32_de503c-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_de503c-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_de503c-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_de503c-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_de503c-bb > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column32_de503c-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_de503c-bb{position:relative;}.kadence-column32_de503c-bb, .kt-inside-inner-col > .kadence-column32_de503c-bb:not(.specificity){margin-top:0px;margin-right:40px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column32_de503c-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_de503c-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_de503c-bb, .kt-inside-inner-col > .kadence-column32_de503c-bb:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_de503c-bb inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:rgba(242, 242, 242, 0);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box32_c7f925-f3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box32_c7f925-f3 .kt-info-svg-icon-flip, .kt-info-box32_c7f925-f3 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-color:#444444;}.kt-info-box32_c7f925-f3 .kt-infobox-textcontent span.kt-blocks-info-box-title{font-size:1em;line-height:1.2em;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_c7f925-f3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);text-align:center;display:block;}.kt-info-box32_c7f925-f3 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box32_c7f925-f3\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><span class=\"kt-blocks-info-box-title\">Certified quality<\/span><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column32_36179f-1d > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_36179f-1d > .kt-inside-inner-col,.kadence-column32_36179f-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_36179f-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_36179f-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_36179f-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_36179f-1d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column32_36179f-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_36179f-1d{position:relative;}.kadence-column32_36179f-1d, .kt-inside-inner-col > .kadence-column32_36179f-1d:not(.specificity){margin-top:0px;margin-right:40px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column32_36179f-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_36179f-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_36179f-1d, .kt-inside-inner-col > .kadence-column32_36179f-1d:not(.specificity){margin-top:20px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_36179f-1d inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:rgba(242, 242, 242, 0);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box32_266055-1e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box32_266055-1e .kt-info-svg-icon-flip, .kt-info-box32_266055-1e .kt-blocks-info-box-number{font-size:50px;}.kt-info-box32_266055-1e .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box32_266055-1e .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-color:#444444;}.kt-info-box32_266055-1e .kt-infobox-textcontent span.kt-blocks-info-box-title{font-size:1em;line-height:1.2em;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_266055-1e .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box32_266055-1e .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);text-align:center;display:block;}.kt-info-box32_266055-1e .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box32_266055-1e\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_trendingUp kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"23 6 13.5 15.5 8.5 10.5 1 18\"\/><polyline points=\"17 6 23 6 23 12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><span class=\"kt-blocks-info-box-title\">Volume-optimized pricing<\/span><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column32_6007ec-15 > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_6007ec-15 > .kt-inside-inner-col,.kadence-column32_6007ec-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_6007ec-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_6007ec-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_6007ec-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_6007ec-15 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column32_6007ec-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_6007ec-15{position:relative;}.kadence-column32_6007ec-15, .kt-inside-inner-col > .kadence-column32_6007ec-15:not(.specificity){margin-top:0px;margin-right:40px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column32_6007ec-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_6007ec-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_6007ec-15, .kt-inside-inner-col > .kadence-column32_6007ec-15:not(.specificity){margin-top:20px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_6007ec-15 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:rgba(242, 242, 242, 0);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box32_99b1ce-95 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box32_99b1ce-95 .kt-info-svg-icon-flip, .kt-info-box32_99b1ce-95 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-color:#444444;}.kt-info-box32_99b1ce-95 .kt-infobox-textcontent span.kt-blocks-info-box-title{font-size:1em;line-height:1.2em;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_99b1ce-95 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);text-align:center;display:block;}.kt-info-box32_99b1ce-95 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box32_99b1ce-95\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_truck kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"1\" y=\"3\" width=\"15\" height=\"13\"\/><polygon points=\"16 8 20 8 23 11 23 16 16 16 16 8\"\/><circle cx=\"5.5\" cy=\"18.5\" r=\"2.5\"\/><circle cx=\"18.5\" cy=\"18.5\" r=\"2.5\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><span class=\"kt-blocks-info-box-title\">Deliveries tailored to your production<\/span><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column32_c58dbd-0d > .kt-inside-inner-col{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kadence-column32_c58dbd-0d > .kt-inside-inner-col,.kadence-column32_c58dbd-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column32_c58dbd-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column32_c58dbd-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column32_c58dbd-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column32_c58dbd-0d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column32_c58dbd-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column32_c58dbd-0d{position:relative;}.kadence-column32_c58dbd-0d, .kt-inside-inner-col > .kadence-column32_c58dbd-0d:not(.specificity){margin-top:0px;margin-right:40px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column32_c58dbd-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column32_c58dbd-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column32_c58dbd-0d, .kt-inside-inner-col > .kadence-column32_c58dbd-0d:not(.specificity){margin-top:20px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column32_c58dbd-0d inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:rgba(242, 242, 242, 0);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box32_2ae08a-b0 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box32_2ae08a-b0 .kt-info-svg-icon-flip, .kt-info-box32_2ae08a-b0 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-color:#444444;}.kt-info-box32_2ae08a-b0 .kt-infobox-textcontent span.kt-blocks-info-box-title{font-size:1em;line-height:1.2em;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:700;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_2ae08a-b0 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette7, #eeeeee);border-right:5px solid var(--global-palette7, #eeeeee);border-bottom:5px solid var(--global-palette7, #eeeeee);border-left:5px solid var(--global-palette7, #eeeeee);text-align:center;display:block;}.kt-info-box32_2ae08a-b0 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box32_2ae08a-b0\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-mobile-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><span class=\"kt-blocks-info-box-title\">Total adaptability to your plans and needs<\/span><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>About Us | Tecnoras S.A Manufacturers of hard metal tools. History and Location At Tecnoras S.A., we have been manufacturing hard metal (tungsten carbide) and steel tools for cold forming metals since our founding in Cornell\u00e0 de Llobregat in July 1987. In 1999, we moved to our current location in an 800 m\u00b2 building in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1023","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Who we are | Industrial tool manufacturing company<\/title>\n<meta name=\"description\" content=\"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecnoras.com\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Who we are | Industrial tool manufacturing company\" \/>\n<meta property=\"og:description\" content=\"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecnoras.com\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"tecnoras\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T11:11:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tecnoras.com\/en\/about-us\/\",\"url\":\"https:\/\/tecnoras.com\/en\/about-us\/\",\"name\":\"Who we are | Industrial tool manufacturing company\",\"isPartOf\":{\"@id\":\"https:\/\/tecnoras.com\/en\/#website\"},\"datePublished\":\"2025-06-12T11:41:20+00:00\",\"dateModified\":\"2025-09-08T11:11:41+00:00\",\"description\":\"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.\",\"breadcrumb\":{\"@id\":\"https:\/\/tecnoras.com\/en\/about-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tecnoras.com\/en\/about-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tecnoras.com\/en\/about-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tecnoras.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tecnoras.com\/en\/#website\",\"url\":\"https:\/\/tecnoras.com\/en\/\",\"name\":\"tecnoras.com\",\"description\":\"Fabricaci\u00f3n de herramientas de metal duro y acero\",\"publisher\":{\"@id\":\"https:\/\/tecnoras.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tecnoras.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tecnoras.com\/en\/#organization\",\"name\":\"TECNORAS, S.A.\",\"url\":\"https:\/\/tecnoras.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tecnoras.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/06\/cropped-logo.jpg\",\"contentUrl\":\"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/06\/cropped-logo.jpg\",\"width\":361,\"height\":297,\"caption\":\"TECNORAS, S.A.\"},\"image\":{\"@id\":\"https:\/\/tecnoras.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Who we are | Industrial tool manufacturing company","description":"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecnoras.com\/en\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"Who we are | Industrial tool manufacturing company","og_description":"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.","og_url":"https:\/\/tecnoras.com\/en\/about-us\/","og_site_name":"tecnoras","article_modified_time":"2025-09-08T11:11:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tecnoras.com\/en\/about-us\/","url":"https:\/\/tecnoras.com\/en\/about-us\/","name":"Who we are | Industrial tool manufacturing company","isPartOf":{"@id":"https:\/\/tecnoras.com\/en\/#website"},"datePublished":"2025-06-12T11:41:20+00:00","dateModified":"2025-09-08T11:11:41+00:00","description":"Who we are at Tecnoras S.A.: an industrial tool manufacturing company with experience, innovation, and a commitment to quality.","breadcrumb":{"@id":"https:\/\/tecnoras.com\/en\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecnoras.com\/en\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tecnoras.com\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tecnoras.com\/en\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/tecnoras.com\/en\/#website","url":"https:\/\/tecnoras.com\/en\/","name":"tecnoras.com","description":"Fabricaci\u00f3n de herramientas de metal duro y acero","publisher":{"@id":"https:\/\/tecnoras.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecnoras.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tecnoras.com\/en\/#organization","name":"TECNORAS, S.A.","url":"https:\/\/tecnoras.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tecnoras.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/06\/cropped-logo.jpg","contentUrl":"https:\/\/tecnoras.com\/wp-content\/uploads\/2025\/06\/cropped-logo.jpg","width":361,"height":297,"caption":"TECNORAS, S.A."},"image":{"@id":"https:\/\/tecnoras.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/pages\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":9,"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/pages\/1023\/revisions"}],"predecessor-version":[{"id":2362,"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/pages\/1023\/revisions\/2362"}],"wp:attachment":[{"href":"https:\/\/tecnoras.com\/en\/wp-json\/wp\/v2\/media?parent=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}